{"id":35426,"date":"2026-05-05T11:30:29","date_gmt":"2026-05-05T09:30:29","guid":{"rendered":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/"},"modified":"2026-05-05T11:30:32","modified_gmt":"2026-05-05T09:30:32","slug":"gellner-pure-5-23798-02","status":"publish","type":"product","link":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/","title":{"rendered":"H2O Ohrstecker"},"content":{"rendered":"<p>Erh\u00e4ltlich bei Goldschmied JUWELIER AM SCHLOSS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erh\u00e4ltlich bei Goldschmied JUWELIER AM SCHLOSS<\/p>\n","protected":false},"featured_media":77680,"comment_status":"closed","ping_status":"open","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"product_cat":[32,103,92,81,153,95,219,91],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS<\/title>\n<meta name=\"description\" content=\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\" \/>\n<meta property=\"og:description\" content=\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Goldschmiede Juwelier Am Schloss\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T09:30:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2026\/05\/gellner-pure-h2o-ohrstecker-5-23798-02-24647991.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/\",\"url\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/\",\"name\":\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\",\"isPartOf\":{\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#website\"},\"datePublished\":\"2026-05-05T09:30:29+00:00\",\"dateModified\":\"2026-05-05T09:30:32+00:00\",\"description\":\"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS\",\"breadcrumb\":{\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H2O Ohrstecker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#website\",\"url\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/\",\"name\":\"Goldschmiede Juwelier Am Schloss\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#organization\",\"name\":\"Goldschmiede Juwelier Am Schloss\",\"url\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2018\/08\/geschwill-juwelier-Logo-2025-neu.png\",\"contentUrl\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2018\/08\/geschwill-juwelier-Logo-2025-neu.png\",\"width\":1000,\"height\":567,\"caption\":\"Goldschmiede Juwelier Am Schloss\"},\"image\":{\"@id\":\"https:\/\/juwelieramschloss.de\/goldschmiede\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","description":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/","og_locale":"de_DE","og_type":"article","og_title":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","og_description":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","og_url":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/","og_site_name":"Goldschmiede Juwelier Am Schloss","article_modified_time":"2026-05-05T09:30:32+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2026\/05\/gellner-pure-h2o-ohrstecker-5-23798-02-24647991.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/","url":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/","name":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","isPartOf":{"@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#website"},"datePublished":"2026-05-05T09:30:29+00:00","dateModified":"2026-05-05T09:30:32+00:00","description":"H2O Ohrstecker von Gellner bei Goldschmied JUWELIER AM SCHLOSS","breadcrumb":{"@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/produkt\/gellner-pure-5-23798-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/juwelieramschloss.de\/goldschmiede\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/juwelieramschloss.de\/goldschmiede\/shop\/"},{"@type":"ListItem","position":3,"name":"H2O Ohrstecker"}]},{"@type":"WebSite","@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#website","url":"https:\/\/juwelieramschloss.de\/goldschmiede\/","name":"Goldschmiede Juwelier Am Schloss","description":"","publisher":{"@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/juwelieramschloss.de\/goldschmiede\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#organization","name":"Goldschmiede Juwelier Am Schloss","url":"https:\/\/juwelieramschloss.de\/goldschmiede\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#\/schema\/logo\/image\/","url":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2018\/08\/geschwill-juwelier-Logo-2025-neu.png","contentUrl":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-content\/uploads\/sites\/4\/2018\/08\/geschwill-juwelier-Logo-2025-neu.png","width":1000,"height":567,"caption":"Goldschmiede Juwelier Am Schloss"},"image":{"@id":"https:\/\/juwelieramschloss.de\/goldschmiede\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/product\/35426"}],"collection":[{"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/comments?post=35426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/media\/77680"}],"wp:attachment":[{"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/media?parent=35426"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/product_cat?post=35426"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/juwelieramschloss.de\/goldschmiede\/wp-json\/wp\/v2\/product_tag?post=35426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}